{"id":15,"count":1,"description":"","link":"https:\/\/www.platts.co.uk\/how-to\/tag\/ford-focus\/","name":"Ford Focus","slug":"ford-focus","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.platts.co.uk\/how-to\/wp-json\/wp\/v2\/tags\/15"}],"collection":[{"href":"https:\/\/www.platts.co.uk\/how-to\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.platts.co.uk\/how-to\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.platts.co.uk\/how-to\/wp-json\/wp\/v2\/posts?tags=15"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}