{"id":21,"count":2,"description":"","link":"https:\/\/www.platts.co.uk\/how-to\/tag\/ford-kuga\/","name":"Ford Kuga","slug":"ford-kuga","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.platts.co.uk\/how-to\/wp-json\/wp\/v2\/tags\/21"}],"collection":[{"href":"https:\/\/www.platts.co.uk\/how-to\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.platts.co.uk\/how-to\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.platts.co.uk\/how-to\/wp-json\/wp\/v2\/posts?tags=21"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}