{"id":36,"count":1,"description":"","link":"https:\/\/www.platts.co.uk\/how-to\/tag\/mobile-apps\/","name":"Mobile Apps","slug":"mobile-apps","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.platts.co.uk\/how-to\/wp-json\/wp\/v2\/tags\/36"}],"collection":[{"href":"https:\/\/www.platts.co.uk\/how-to\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.platts.co.uk\/how-to\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.platts.co.uk\/how-to\/wp-json\/wp\/v2\/posts?tags=36"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}